{"id":856,"date":"2012-05-24T07:22:25","date_gmt":"2012-05-24T07:22:25","guid":{"rendered":"http:\/\/pichak.net\/crop\/2012\/05\/24\/%d8%a7%d8%b3%d8%aa%d9%81%d8%a7%d8%af%d9%87-%d8%a7%d8%b2-%d8%b4%db%8c%d8%b1-%e2%80%9c%d8%b4%d9%86%da%af%d9%88%d9%84%e2%80%9d-%d9%88-%e2%80%9c%d9%85%d9%86%da%af%d9%88%d9%84%e2%80%9d-%d8%a8%d8%b1%d8%a7\/"},"modified":"2022-01-19T13:54:25","modified_gmt":"2022-01-19T10:24:25","slug":"%d8%a7%d8%b3%d8%aa%d9%81%d8%a7%d8%af%d9%87-%d8%a7%d8%b2-%d8%b4%db%8c%d8%b1-%d8%b4%d9%86%da%af%d9%88%d9%84-%d9%88-%d9%85%d9%86%da%af%d9%88%d9%84-%d8%a8%d8%b1%d8%a7","status":"publish","type":"post","link":"https:\/\/pichak.net\/crop\/1391\/03\/04\/%d8%a7%d8%b3%d8%aa%d9%81%d8%a7%d8%af%d9%87-%d8%a7%d8%b2-%d8%b4%db%8c%d8%b1-%d8%b4%d9%86%da%af%d9%88%d9%84-%d9%88-%d9%85%d9%86%da%af%d9%88%d9%84-%d8%a8%d8%b1%d8%a7\/","title":{"rendered":"\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0634\u06cc\u0631 \u201c\u0634\u0646\u06af\u0648\u0644\u201d \u0648 \u201c\u0645\u0646\u06af\u0648\u0644\u201d \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u062e\u0648\u0646\u06cc"},"content":{"rendered":"<p style=\"text-align: center\">\n<p dir=\"RTL\">\u0627\u06cc\u0646 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a &#8220;\u0634\u0646\u06af\u0648\u0644 \u0648 \u0645\u0646\u06af\u0648\u0644 &#8221; \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0633\u062a\u06a9\u0627\u0631\u06cc \u0634\u062f\u0647 \u0648 \u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u0698\u0646\u062a\u06cc\u06a9\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0634\u06cc\u0631\u0634\u0627\u0646 \u067e\u0631\u0648\u062a\u06cc\u0646 \u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f&#8230;<\/p>\n<p dir=\"RTL\"><span style=\"color: #ff0000\"><strong>\u0628\u0642\u06cc\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0637\u0644\u0628<\/strong><\/span><\/p>\n<p dir=\"RTL\"><span id=\"more-4839\"><\/span><\/p>\n<p dir=\"RTL\">\n<p dir=\"RTL\">\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u062a\u06a9\u062a\u0631\u06cc\u0646\u060c \u0645\u062d\u0645\u062f \u062d\u0633\u06cc\u0646 \u06cc\u0627\u062f\u06af\u0627\u0631\u06cc \u0686\u0647\u0627\u0631\u0634\u0646\u0628\u0647 \u0634\u0628 \u062f\u0631 \u0646\u0634\u0633\u062a \u062e\u0628\u0631\u06cc \u0628\u0631\u0631\u0633\u06cc \u062f\u0633\u062a\u0627\u0648\u0631\u062f\u0647\u0627\u06cc \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0627\u0641\u0632\u0648\u062f: \u062f\u0631 \u0634\u06cc\u0631 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u062a\u0631\u0627\u0631\u06cc\u062e\u062a\u0647 \u067e\u0631\u0648\u062a\u0626\u06cc\u0646 \u0647\u0627\u06cc\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627\u06cc \u062e\u0648\u0646\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647\u0631\u0647 \u0628\u0631\u062f.<\/p>\n<p>\u0648\u06cc \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u0627\u06cc\u0646 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a &#8220;\u0634\u0646\u06af\u0648\u0644 \u0648 \u0645\u0646\u06af\u0648\u0644 &#8221; \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0633\u062a\u06a9\u0627\u0631\u06cc \u0634\u062f\u0647 \u0648 \u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u0698\u0646\u062a\u06cc\u06a9\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0634\u06cc\u0631\u0634\u0627\u0646 \u067e\u0631\u0648\u062a\u06cc\u0646 \u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f.<\/p>\n<p>\u0648\u06cc \u0639\u0646\u0648\u0627\u0646 \u06a9\u0631\u062f: \u0645\u0627 \u062f\u0631 \u0631\u0634\u062a\u0647 \u0647\u0627\u06cc \u0639\u0644\u0648\u0645 \u067e\u0632\u0634\u06a9\u06cc\u060c \u0641\u0646\u06cc \u0645\u0647\u0646\u062f\u0633\u06cc\u060c \u0639\u0644\u0648\u0645 \u067e\u0627\u06cc\u0647\u060c \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u0647\u0646\u0631\u060c \u0639\u0644\u0648\u0645 \u0645\u0647\u0646\u062f\u0633\u06cc \u0648 ..\u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062e\u0648\u0628\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u06cc\u0645.<br \/>\n<strong><br \/>\n\u0627\u062c\u0631\u0627\u06cc \u06f1\u06f3 \u062f\u06a9\u0644 \u062d\u0641\u0627\u0631\u06cc \u0646\u0641\u062a<\/strong><\/p>\n<p>\u06cc\u0627\u062f\u06af\u0627\u0631\u06cc \u0627\u0641\u0632\u0648\u062f: \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062f\u0631 \u0628\u062e\u0634 \u0641\u0646\u06cc \u0648 \u0645\u0647\u0646\u062f\u0633\u06cc \u0628\u0647 \u062d\u0648\u0632\u0647 \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0648\u0631\u0648\u062f \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0627 \u0627\u0639\u062a\u0645\u0627\u062f\u06cc \u06a9\u0647 \u0648\u0632\u0627\u0631\u062a \u0646\u0641\u062a \u0628\u0647 \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u06f1\u06f3 \u062f\u06a9\u0644 \u062d\u0641\u0627\u0631\u06cc \u0646\u0641\u062a \u0631\u0627 \u062f\u0631 \u0628\u062e\u0634 \u062e\u0634\u06a9\u06cc \u0628\u0631 \u0639\u0647\u062f\u0647 \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u06af\u0630\u0627\u0634\u062a\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0631\u0626\u06cc\u0633 \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u06a9\u0634\u0648\u0631 \u0627\u0641\u0632\u0648\u062f: \u0627\u0648\u0627\u0633\u0637 \u0633\u0627\u0644 \u062c\u0627\u0631\u06cc \u0648 \u06cc\u0627 \u062f\u0631 \u067e\u0627\u06cc\u06cc\u0632 \u0627\u0648\u0644\u06cc\u0646 \u062f\u06a9\u0644 \u062d\u0641\u0627\u0631\u06cc \u0646\u0641\u062a \u0628\u0627 \u0647\u0645\u062a \u0646\u06cc\u0631\u0648\u0647\u0627\u06cc \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u062f\u0631 \u0646\u0638\u0627\u0645 \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u0646\u062c\u0627\u0645 \u062e\u0648\u0627\u0647\u062f \u0634\u062f.<br \/>\n<strong><br \/>\n\u0627\u06cc\u062c\u0627\u062f \u0645\u0631\u06a9\u0632 \u062f\u0631\u0645\u0627\u0646 \u062a\u062e\u0635\u0635\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u06cc \u062f\u0631 \u06af\u0644\u0633\u062a\u0627\u0646<\/strong><\/p>\n<p>\u06cc\u0627\u062f\u06af\u0627\u0631\u06cc \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u062f\u0633\u062a\u0627\u0648\u0631\u062f\u0647\u0627\u06cc \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u062f\u0631 \u06f3\u06f2 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u0628\u0647 \u0645\u0635\u0648\u0628\u0627\u062a \u0633\u0641\u0631 \u062e\u0648\u062f \u062f\u0631 \u06af\u0644\u0633\u062a\u0627\u0646 \u0627\u0634\u0627\u0631\u0647 \u0648 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f: \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0645\u0647\u0645\u060c \u062f\u0631\u0645\u0627\u0646 \u062a\u062e\u0635\u0635\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0627\u0633\u062a\u0627\u0646 \u0627\u0633\u062a.<\/p>\n<p>\u0648\u06cc \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u0628\u0627 \u0635\u062d\u0628\u062a\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0634\u062f\u0647 \u0645\u0628\u0646\u06cc \u0628\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u0632\u0645\u06cc\u0646\u0647 \u0627\u06cc \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u0646\u062f \u062a\u0627 \u062e\u062f\u0645\u0627\u062a \u062a\u062e\u0635\u0635\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u06cc \u0628\u0631\u0627\u06cc \u062e\u062f\u0645\u062a \u0628\u0647 \u0645\u0631\u062f\u0645 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0627\u0633\u062a\u0627\u0646\u0647\u0627\u06cc \u0647\u0645\u062c\u0648\u0627\u0631 \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u062f.<\/p>\n<p>\u06cc\u0627\u062f\u06af\u0627\u0631\u06cc \u0627\u0641\u0632\u0648\u062f: \u0642\u0631\u0627\u0631 \u0634\u062f \u0645\u0627 \u0632\u0645\u06cc\u0646\u0647 \u0647\u0627\u06cc \u0639\u0644\u0645\u06cc \u0648 \u0627\u0633\u062a\u0627\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0647\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631\u0633\u062a\u0627\u0646\u06cc \u0648 \u062a\u062e\u0635\u0635\u06cc \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u062f.<\/p>\n<p>\u0631\u0626\u06cc\u0633 \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u06a9\u0634\u0648\u0631 \u06af\u0641\u062a: \u0632\u0645\u06cc\u0646\u0647 \u0647\u0627\u06cc \u06af\u06cc\u0627\u0647\u0627\u0646 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0648 \u0648\u0631\u0648\u062f \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0627\u0632 \u062f\u06cc\u06af\u0631 \u0628\u062d\u062b \u0647\u0627\u06cc \u0627\u0633\u0627\u0633\u06cc \u0627\u0633\u062a.<\/p>\n<p><strong>\u062a\u062d\u0642\u06cc\u0642 \u0631\u0648\u06cc \u06af\u06cc\u0627\u0647\u0627\u0646 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u0648\u0645\u06cc<\/strong><\/p>\n<p>\u0648\u06cc \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u067e\u0698\u0648\u0647\u0634\u06a9\u062f\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0645\u0627 \u0627\u06a9\u0646\u0648\u0646 \u062f\u0631 \u062a\u0647\u0631\u0627\u0646 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0627\u0631\u0632\u0646\u062f\u0647 \u0627\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u0633\u062a\u062d\u0635\u0627\u0644 \u06af\u06cc\u0627\u0647\u0627\u0646 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u06cc\u0627\u062f\u06af\u0627\u0631\u06cc \u06cc\u0627\u062f\u0622\u0648\u0631\u0634\u062f: \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0627 \u0645\u0633\u0626\u0648\u0644\u0627\u0646 \u0627\u0633\u062a\u0627\u0646 \u06af\u0644\u0633\u062a\u0627\u0646 \u0635\u062d\u0628\u062a \u0634\u062f\u0647 \u06a9\u0647 \u0632\u0645\u06cc\u0646\u0647 \u0647\u0627\u06cc\u06cc \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u062f \u062a\u0627 \u0631\u0648\u06cc \u06af\u06cc\u0627\u0647\u0627\u0646 \u0628\u0648\u0645\u06cc \u062a\u0627\u062b\u06cc\u0631 \u06af\u0630\u0627\u0631 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627 \u062a\u062d\u0642\u06cc\u0642 \u0635\u0648\u0631\u062a \u06af\u06cc\u0631\u062f.<\/p>\n<p>\u0648\u06cc \u0628\u0631\u0627\u06cc \u0634\u0631\u06a9\u062a \u062f\u0631 \u0633\u06cc \u0648 \u067e\u0646\u062c\u0645\u06cc\u0646 \u06af\u0631\u062f\u0647\u0645\u0627\u06cc\u06cc \u0645\u0639\u0627\u0648\u0646\u0627\u0646 \u0622\u0645\u0648\u0632\u0634\u06cc \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u067e\u0698\u0648\u0647\u0634\u06a9\u062f\u0647 \u0647\u0627 \u0648 \u0633\u0627\u0632\u0645\u0627\u0646 \u0648 \u0645\u0631\u0627\u06a9\u0632 \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0633\u0631\u0627\u0633\u0631 \u06a9\u0634\u0648\u0631 \u0628\u0647 \u06af\u0644\u0633\u062a\u0627\u0646 \u0633\u0641\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u062a\u06a9 \u062a\u0631\u06cc\u0646 \u0633\u0627\u06cc\u0640\u062a \u0627\u06cc\u0640\u0631\u0627\u0646\u06cc<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u06cc\u0646 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a &#8220;\u0634\u0646\u06af\u0648\u0644 \u0648 \u0645\u0646\u06af\u0648\u0644 &#8221; \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0633\u062a\u06a9\u0627\u0631\u06cc \u0634\u062f\u0647 \u0648 \u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u0698\u0646\u062a\u06cc\u06a9\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0634\u06cc\u0631\u0634\u0627\u0646 \u067e\u0631\u0648\u062a\u06cc\u0646 \u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f&#8230; \u0628\u0642\u06cc\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0637\u0644\u0628 \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u062a\u06a9\u062a\u0631\u06cc\u0646\u060c \u0645\u062d\u0645\u062f \u062d\u0633\u06cc\u0646 \u06cc\u0627\u062f\u06af\u0627\u0631\u06cc \u0686\u0647\u0627\u0631\u0634\u0646\u0628\u0647 \u0634\u0628 \u062f\u0631 \u0646\u0634\u0633\u062a \u062e\u0628\u0631\u06cc \u0628\u0631\u0631\u0633\u06cc \u062f\u0633\u062a\u0627\u0648\u0631\u062f\u0647\u0627\u06cc \u062c\u0647\u0627\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0627\u0641\u0632\u0648\u062f: \u062f\u0631 \u0634\u06cc\u0631 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u062a\u0631\u0627\u0631\u06cc\u062e\u062a\u0647 &hellip; <a href=\"https:\/\/pichak.net\/crop\/1391\/03\/04\/%d8%a7%d8%b3%d8%aa%d9%81%d8%a7%d8%af%d9%87-%d8%a7%d8%b2-%d8%b4%db%8c%d8%b1-%d8%b4%d9%86%da%af%d9%88%d9%84-%d9%88-%d9%85%d9%86%da%af%d9%88%d9%84-%d8%a8%d8%b1%d8%a7\/\" class=\"more-link\">\u0627\u062f\u0627\u0645\u0647 \u062e\u0648\u0627\u0646\u062f\u0646 <span class=\"screen-reader-text\">\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0634\u06cc\u0631 \u201c\u0634\u0646\u06af\u0648\u0644\u201d \u0648 \u201c\u0645\u0646\u06af\u0648\u0644\u201d \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0647\u0627\u06cc \u062e\u0648\u0646\u06cc<\/span> <span class=\"meta-nav\">&larr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[38],"tags":[2284,2285,13,1054,129,1338,47,1522,1564,55],"_links":{"self":[{"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/posts\/856"}],"collection":[{"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/comments?post=856"}],"version-history":[{"count":3,"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/posts\/856\/revisions"}],"predecessor-version":[{"id":16696,"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/posts\/856\/revisions\/16696"}],"wp:attachment":[{"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/media?parent=856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/categories?post=856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pichak.net\/crop\/wp-json\/wp\/v2\/tags?post=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}